{"id":18614,"date":"2024-08-01T09:00:00","date_gmt":"2024-08-01T13:00:00","guid":{"rendered":"https:\/\/endhomelessness.org\/blog\/creacion-de-un-sistema-eficaz-contra-la-falta-de-vivienda-aprovechamiento-del-concurso-del-programa-coc-nofo-para-los-anos-fiscales-2024-25\/"},"modified":"2025-04-08T08:13:10","modified_gmt":"2025-04-08T12:13:10","slug":"creacion-de-un-sistema-eficaz-contra-la-falta-de-vivienda-aprovechamiento-del-concurso-del-programa-coc-nofo-para-los-anos-fiscales-2024-25","status":"publish","type":"blog","link":"https:\/\/endhomelessness.org\/es\/blog\/creacion-de-un-sistema-eficaz-contra-la-falta-de-vivienda-aprovechamiento-del-concurso-del-programa-coc-nofo-para-los-anos-fiscales-2024-25\/","title":{"rendered":"Creaci\u00f3n de un sistema eficaz contra la falta de vivienda: Aprovechamiento del concurso del programa CoC NOFO para los a\u00f1os fiscales 2024\/25"},"content":{"rendered":"\n<section class=\"e-stn e-stn-642edd2d478cb6d72ad11a3f94eb096b46aa8c61 e-stn--bi-banner e-stn--blog-inner-banner e-mt-0\"><div class=\"container\">\n<div class=\"wp-block-b3rg-row e-row row\">\n<div class=\"wp-block-b3rg-column e-col e-col-a1723a90dcabee317021282e0a59fa1add95d7a3 e-col--blog-inner-banner-content-wrpr  col-sm-12 col-lg-6\">\n<div class=\"e-div e-div-368784d6f024bd28fc93462eb0616dec8d069665 e-div--blog-inner-post-type-tag\"><span>BLOG<\/span>\n<\/div>\n\n\n<div class=\"e-mtf e-mtf--dlt  e-mtf--post-date\">May 13, 2026<\/div>\n\n<h1 class=\"wp-block-post-title\">Creaci\u00f3n de un sistema eficaz contra la falta de vivienda: Aprovechamiento del concurso del programa CoC NOFO para los a\u00f1os fiscales 2024\/25<\/h1>\n\n\n<div class=\"e-div e-div-976a3f7724ffcd71e737afe4e1bbffbbf3dd036f e-div--bi-read-time\"><div class=\"e-mtf e-mtf--dlt  e-mtf--author-with-link\"><a href=\"https:\/\/endhomelessness.org\/es\/author\/mkenion\/\" class=\"post-author-url\">\n    <div class=\"post-author\">            <div class=\"post-author__content\">\n                <p class=\"post-author__name\">Mary Frances Kenion<\/p>\n            <\/div>\n        <\/div>\n    <\/a><\/div>\n\n\n<div class=\"e-div e-div-0162dd5adc5b84600d5bea230d8c418559af071d\"><div class=\"e-mtf e-mtf--dlt  e-mtf--post-reading-time\"><div class=\"post-reading-time\"><span class=\"reading-time__time\">4<\/span> <span class=\"post-reading-time__label postfix\">min<\/span><\/div><\/div><\/div>\n<\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-b3rg-column e-col e-col-0c503a5984f4fbd04e91061f205fb824382fb9a6 e-col--blog-inner-banner-media-wrpr  col-sm-12 col-lg-6\"><figure class=\"wp-block-post-featured-image\"><img decoding=\"async\" src=\"https:\/\/endhomelessness.org\/wp-content\/uploads\/2024\/10\/Nesbitt-Woman-typing-computer-3-1-e1531943208769.jpg\" class=\"attachment-post-thumbnail size-post-thumbnail wp-post-image\" alt=\"Nesbitt Woman typing computer\" style=\"object-fit:cover;\" srcset=\"https:\/\/endhomelessness.org\/wp-content\/uploads\/2024\/10\/Nesbitt-Woman-typing-computer-3-1-e1531943208769.jpg 877w, https:\/\/endhomelessness.org\/wp-content\/uploads\/2024\/10\/Nesbitt-Woman-typing-computer-3-1-e1531943208769-300x137.jpg 300w, https:\/\/endhomelessness.org\/wp-content\/uploads\/2024\/10\/Nesbitt-Woman-typing-computer-3-1-e1531943208769-768x350.jpg 768w, https:\/\/endhomelessness.org\/wp-content\/uploads\/2024\/10\/Nesbitt-Woman-typing-computer-3-1-e1531943208769-575x262.jpg 575w\" sizes=\"(max-width: 877px) 100vw, 877px\" \/><\/figure><\/div>\n<\/div>\n<\/div><\/section>\n\n<section class=\"e-stn e-stn-ad75c7bf6c94c4c74b1ce488ab717de8fdff6ca2 e-stn--bi-content-with-media-section e-mt-0 e-pt-120  e-pt-sm-50 e-pb-60\"><div class=\"container\">\n<div class=\"wp-block-b3rg-row e-row row\">\n<div class=\"wp-block-b3rg-column e-col e-col-f1092f68b065a750a7ad99323cbd3499d1ad2b1c e-col--bi-content-with-media-section-content-wrapper e-col--blog-inner-contents  col-sm-12 col-lg-9\">\n<p class=\"has-midnight-express-color has-text-color has-link-color wp-elements-be8ca5e6422c5c43e3042cd94c104530\">El Departamento de Vivienda y Desarrollo Urbano de los Estados Unidos (HUD) ha puesto recientemente a disposici\u00f3n 3.524 millones de d\u00f3lares en financiaci\u00f3n a trav\u00e9s del <a href=\"https:\/\/grants.gov\/search-results-detail\/355762\" target=\"_blank\" rel=\"noreferrer noopener\">Concurso del Programa de Continuidad de Cuidados para los a\u00f1os fiscales 2024 y 2025 y la Renovaci\u00f3n o Sustituci\u00f3n de las Subvenciones del Programa de Demostraci\u00f3n para J\u00f3venes sin Hogar.<\/a><\/p>\n\n\n\n<p>El equipo de la Alianza deseaba proporcionar informaci\u00f3n sobre los cambios clave para este a\u00f1o. Junto con un aumento del 12,44 por ciento sobre la financiaci\u00f3n del a\u00f1o fiscal 2023, hay algunos cambios notables respecto al NOFO anterior: <\/p>\n\n\n\n<div class=\"e-div e-div-9ce29f63ba27703dc1c62e7641a10a0714efe0cc e-div--blog-inner-highlight-content\">\n<p><strong>Construcci\u00f3n de una fuerza laboral eficaz<\/strong>. El a\u00f1o pasado, el Instituto de Investigaci\u00f3n sobre la Falta de Vivienda de la Alianza public\u00f3 hallazgos clave de una <a href=\"\/resources\/research-and-analysis\/working-in-homeless-services-a-survey-of-the-field\/\">encuesta del campo<\/a> que identificaba los bajos salarios, la alta rotaci\u00f3n y la falta de recursos como desaf\u00edos fundamentales de la fuerza laboral. HUD ha a\u00f1adido una nueva Prioridad de Pol\u00edtica para Personas sin Hogar al NOFO del Concurso del Programa CoC este a\u00f1o, reconociendo estos desaf\u00edos y alentando a los CoC a trabajar con financiadores y partes interesadas para mejorar la remuneraci\u00f3n y el apoyo a las personas que trabajan en el sector de la falta de vivienda.  <\/p>\n<\/div>\n\n\n\n<div class=\"e-div e-div-9ce29f63ba27703dc1c62e7641a10a0714efe0cc e-div--blog-inner-highlight-content\">\n<p><strong>Ciclo bienal para las solicitudes NOFO.<\/strong> Para los a\u00f1os fiscales 2024 y 2025, se emiti\u00f3 una Notificaci\u00f3n de Oportunidad de Financiaci\u00f3n bienal, que incluye procedimientos o requisitos alternativos seg\u00fan sea necesario para asignar futuras apropiaciones en el segundo a\u00f1o, para la adjudicaci\u00f3n de cantidades disponibles para el programa de Continuidad de Cuidados.<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>El proceso de solicitud y selecci\u00f3n para los fondos del a\u00f1o fiscal 2024 proceder\u00e1 de manera similar a como lo ha hecho en concursos de a\u00f1os anteriores.<\/li>\n\n\n\n<li>Los CoC solo est\u00e1n obligados a presentar una solicitud de CoC que ser\u00e1 aplicable tanto a los fondos del a\u00f1o fiscal 2024 como a los del a\u00f1o fiscal 2025.<\/li>\n\n\n\n<li>HUD se reserva el derecho de adjudicar los fondos disponibles para el a\u00f1o fiscal 2025 bas\u00e1ndose en este concurso NOFO.<\/li>\n\n\n\n<li>Si se dispone de nueva financiaci\u00f3n competitiva para el a\u00f1o fiscal 2025, este NOFO podr\u00eda ser modificado, y la solicitud y puntuaci\u00f3n del CoC para los a\u00f1os fiscales 2024-2025 podr\u00edan utilizarse para el proceso de selecci\u00f3n de solicitudes.<\/li>\n\n\n\n<li>Si las asignaciones presupuestarias para el a\u00f1o fiscal 2025 no pueden financiar completamente todas las subvenciones de renovaci\u00f3n del a\u00f1o fiscal 2025, los montos de las subvenciones podr\u00edan reducirse proporcionalmente.<\/li>\n<\/ul>\n<\/div>\n\n\n\n<div class=\"e-div e-div-9ce29f63ba27703dc1c62e7641a10a0714efe0cc e-div--blog-inner-highlight-content\">\n<p><strong>Ajustes por costo de vida para subvenciones seleccionadas condicionalmente.<\/strong> HUD est\u00e1 autorizado a realizar ajustes razonables por costo de vida a los montos de renovaci\u00f3n, lo que puede ayudar a las organizaciones a afrontar el aumento de los costos de operaci\u00f3n debido a la inflaci\u00f3n. HUD ajustar\u00e1 los montos para las l\u00edneas presupuestarias de costos de servicios de apoyo y HMIS para proyectos en renovaci\u00f3n bas\u00e1ndose en el promedio de cambios de los \u00faltimos tres a\u00f1os en el Censo Trimestral Estatal de Empleo y Salarios (QCEQ) para la categor\u00eda de Asistencia Social. <\/p>\n<\/div>\n\n\n\n<div class=\"e-div e-div-9ce29f63ba27703dc1c62e7641a10a0714efe0cc e-div--blog-inner-highlight-content\">\n<p><strong>Cambios en la estratificaci\u00f3n.<\/strong> El Nivel 1 se establece en el 90 por ciento de la Demanda de Renovaci\u00f3n Anual (ARD) del CoC para este NOFO.<\/p>\n<\/div>\n\n\n\n<p>El plazo de presentaci\u00f3n del NOFO del Concurso del Programa CoC de este a\u00f1o es el <strong>30 de octubre de 2024 a las 5:00 P.M. PT \/ 8:00 P.M. ET  <\/strong>. Pero m\u00e1s all\u00e1 de la solicitud del NOFO de este a\u00f1o, los CoC deben pensar ahora en la planificaci\u00f3n general y utilizar el a\u00f1o sin NOFO para recalibrar su sistema.<\/p>\n\n\n\n<p><strong>He aqu\u00ed varias formas de comenzar:<\/strong><\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Integrar a personas con experiencia vivida actual y reciente o <a href=\"https:\/\/endhomelessness.org\/wp-content\/uploads\/2024\/10\/COVID-19-Homeless-System-Response-Engaging-Individuals-with-Lived-Expertise.pdf\" target=\"_blank\" rel=\"noreferrer noopener\">experticia<\/a> en materia de falta de vivienda en todos los aspectos de su trabajo (antes, durante y despu\u00e9s del proceso NOFO).<\/li>\n\n\n\n<li>Revisar el desempe\u00f1o y la fidelidad del programa de los proyectos para proporcionar retroalimentaci\u00f3n sobre el rendimiento.<\/li>\n\n\n\n<li>Establecer y comunicar las expectativas de desempe\u00f1o para los proyectos CoC, especialmente en lo que respecta a la reducci\u00f3n de las disparidades raciales en los resultados y el n\u00famero de personas que se trasladan a viviendas permanentes.<\/li>\n\n\n\n<li>Hablar sobre la reasignaci\u00f3n temprana y continuamente: desarrollar una estrategia de reasignaci\u00f3n como CoC para que no haya sorpresas y todos los socios tengan claras las reasignaciones voluntarias e involuntarias.<\/li>\n\n\n\n<li>Participar en la mejora continua de la calidad para perfeccionar la fidelidad a Housing First, el desempe\u00f1o y la equidad en los resultados.<\/li>\n\n\n\n<li>Fortalecer y simplificar las asociaciones con su autoridad de vivienda p\u00fablica (PHA) para garantizar que m\u00e1s personas sin hogar sean alojadas r\u00e1pidamente.<\/li>\n<\/ul>\n\n\n\n<h2 class=\"wp-block-heading\">Recursos de la Alianza<\/h2>\n\n\n\n<p>La Alianza organizar\u00e1 un seminario web sobre el NOFO de CoC el mi\u00e9rcoles 28 de agosto de 9:00 a 10:30 A.M. PT \/12:00 a 1:30 P.M. ET \u2013 por favor reg\u00edstrese aqu\u00ed para asistir.  <\/p>\n\n\n\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"768\" height=\"402\" src=\"https:\/\/endhomelessness.org\/wp-content\/uploads\/2024\/10\/8-28-2024_Webinar-Sharedlink-768x402-1.jpg\" alt=\"\" class=\"wp-image-5167\" srcset=\"https:\/\/endhomelessness.org\/wp-content\/uploads\/2024\/10\/8-28-2024_Webinar-Sharedlink-768x402-1.jpg 768w, https:\/\/endhomelessness.org\/wp-content\/uploads\/2024\/10\/8-28-2024_Webinar-Sharedlink-768x402-1-300x157.jpg 300w, https:\/\/endhomelessness.org\/wp-content\/uploads\/2024\/10\/8-28-2024_Webinar-Sharedlink-768x402-1-575x301.jpg 575w\" sizes=\"auto, (max-width: 768px) 100vw, 768px\" \/><\/figure>\n\n\n\n<p>Mientras tanto, consulte los recursos actualizados de la Alianza sobre el NOFO del Concurso del Programa CoC:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Lo que se debe y no se debe hacer en el NOFO del Concurso del Programa CoC para los a\u00f1os fiscales 2024\/25<\/li>\n\n\n\n<li>Comparaci\u00f3n de la tabla de puntuaci\u00f3n del CoC<\/li>\n\n\n\n<li><a href=\"\/resources\/toolkits-and-training-materials\/\/roundtable-series-stronger-together-a-roadmap-to-an-effective-homeless-system\/\">M\u00e1s fuertes juntos: Una hoja de ruta hacia una serie de sistemas eficaces para personas sin hogar<\/a>, que proporciona a las comunidades informaci\u00f3n sobre c\u00f3mo volver al uso de las mejores pr\u00e1cticas dentro del sistema de respuesta a la falta de vivienda<\/li>\n<\/ul>\n<\/div>\n\n\n\n<div class=\"wp-block-b3rg-column e-col e-col-07ab2b4105c7c9441fb36c05bc0c1bc8023c6e2c e-col--bi-right-side e-col--blog-inner-related-posts  col-sm-12 col-lg-3\">\n<div class=\"e-div e-div-59078f910ce4d15d28fcab7c9003952a96233d13 e-div--js-bi-sticky-left\">\n<div class=\"e-div e-div-6ff6ea2961c0f998010e1194547bb1cb17285b20 e-div--bi-social-icons\">\n<div class=\"e-div e-div-8fd4c05a3f9dd204e3dd79e614332da9f57f6b56 e-div--social-share-tooltip\"><div class=\"heateor_sss_sharing_container heateor_sss_horizontal_sharing\" data-heateor-ss-offset=\"0\" data-heateor-sss-href='https:\/\/endhomelessness.org\/es\/blog\/creacion-de-un-sistema-eficaz-contra-la-falta-de-vivienda-aprovechamiento-del-concurso-del-programa-coc-nofo-para-los-anos-fiscales-2024-25\/'><div class=\"heateor_sss_sharing_ul\"><a aria-label=\"Copy Link\" class=\"heateor_sss_button_copy_link\" title=\"Copy Link\" rel=\"noopener\" href=\"https:\/\/endhomelessness.org\/es\/blog\/creacion-de-un-sistema-eficaz-contra-la-falta-de-vivienda-aprovechamiento-del-concurso-del-programa-coc-nofo-para-los-anos-fiscales-2024-25\/\" onclick=\"event.preventDefault()\" style=\"font-size:32px!important;box-shadow:none;display:inline-block;vertical-align:middle\"><span class=\"heateor_sss_svg heateor_sss_s__default heateor_sss_s_copy_link\" style=\"background-color:#ffc112;width:35px;height:35px;border-radius:999px;display:inline-block;opacity:1;float:left;font-size:32px;box-shadow:none;display:inline-block;font-size:16px;padding:0 4px;vertical-align:middle;background-repeat:repeat;overflow:hidden;padding:0;cursor:pointer;box-sizing:content-box\"><svg style=\"display:block;border-radius:999px;\" focusable=\"false\" aria-hidden=\"true\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"100%\" height=\"100%\" viewBox=\"-4 -4 40 40\"><path fill=\"#fff\" d=\"M24.412 21.177c0-.36-.126-.665-.377-.917l-2.804-2.804a1.235 1.235 0 0 0-.913-.378c-.377 0-.7.144-.97.43.026.028.11.11.255.25.144.14.24.236.29.29s.117.14.2.256c.087.117.146.232.177.344.03.112.046.236.046.37 0 .36-.126.666-.377.918a1.25 1.25 0 0 1-.918.377 1.4 1.4 0 0 1-.373-.047 1.062 1.062 0 0 1-.345-.175 2.268 2.268 0 0 1-.256-.2 6.815 6.815 0 0 1-.29-.29c-.14-.142-.223-.23-.25-.254-.297.28-.445.607-.445.984 0 .36.126.664.377.916l2.778 2.79c.243.243.548.364.917.364.36 0 .665-.118.917-.35l1.982-1.97c.252-.25.378-.55.378-.9zm-9.477-9.504c0-.36-.126-.665-.377-.917l-2.777-2.79a1.235 1.235 0 0 0-.913-.378c-.35 0-.656.12-.917.364L7.967 9.92c-.254.252-.38.553-.38.903 0 .36.126.665.38.917l2.802 2.804c.242.243.547.364.916.364.377 0 .7-.14.97-.418-.026-.027-.11-.11-.255-.25s-.24-.235-.29-.29a2.675 2.675 0 0 1-.2-.255 1.052 1.052 0 0 1-.176-.344 1.396 1.396 0 0 1-.047-.37c0-.36.126-.662.377-.914.252-.252.557-.377.917-.377.136 0 .26.015.37.046.114.03.23.09.346.175.117.085.202.153.256.2.054.05.15.148.29.29.14.146.222.23.25.258.294-.278.442-.606.442-.983zM27 21.177c0 1.078-.382 1.99-1.146 2.736l-1.982 1.968c-.745.75-1.658 1.12-2.736 1.12-1.087 0-2.004-.38-2.75-1.143l-2.777-2.79c-.75-.747-1.12-1.66-1.12-2.737 0-1.106.392-2.046 1.183-2.818l-1.186-1.185c-.774.79-1.708 1.186-2.805 1.186-1.078 0-1.995-.376-2.75-1.13l-2.803-2.81C5.377 12.82 5 11.903 5 10.826c0-1.08.382-1.993 1.146-2.738L8.128 6.12C8.873 5.372 9.785 5 10.864 5c1.087 0 2.004.382 2.75 1.146l2.777 2.79c.75.747 1.12 1.66 1.12 2.737 0 1.105-.392 2.045-1.183 2.817l1.186 1.186c.774-.79 1.708-1.186 2.805-1.186 1.078 0 1.995.377 2.75 1.132l2.804 2.804c.754.755 1.13 1.672 1.13 2.75z\"\/><\/svg><\/span><\/a><a aria-label=\"Facebook\" class=\"heateor_sss_facebook\" href=\"https:\/\/www.facebook.com\/sharer\/sharer.php?u=https%3A%2F%2Fendhomelessness.org%2Fes%2Fblog%2Fcreacion-de-un-sistema-eficaz-contra-la-falta-de-vivienda-aprovechamiento-del-concurso-del-programa-coc-nofo-para-los-anos-fiscales-2024-25%2F\" title=\"Facebook\" rel=\"nofollow noopener\" target=\"_blank\" style=\"font-size:32px!important;box-shadow:none;display:inline-block;vertical-align:middle\"><span class=\"heateor_sss_svg\" style=\"background-color:#0765FE;width:35px;height:35px;border-radius:999px;display:inline-block;opacity:1;float:left;font-size:32px;box-shadow:none;display:inline-block;font-size:16px;padding:0 4px;vertical-align:middle;background-repeat:repeat;overflow:hidden;padding:0;cursor:pointer;box-sizing:content-box\"><svg style=\"display:block;border-radius:999px;\" focusable=\"false\" aria-hidden=\"true\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"100%\" height=\"100%\" viewBox=\"0 0 32 32\"><path fill=\"#fff\" d=\"M28 16c0-6.627-5.373-12-12-12S4 9.373 4 16c0 5.628 3.875 10.35 9.101 11.647v-7.98h-2.474V16H13.1v-1.58c0-4.085 1.849-5.978 5.859-5.978.76 0 2.072.15 2.608.298v3.325c-.283-.03-.775-.045-1.386-.045-1.967 0-2.728.745-2.728 2.683V16h3.92l-.673 3.667h-3.247v8.245C23.395 27.195 28 22.135 28 16Z\"><\/path><\/svg><\/span><\/a><a aria-label=\"Linkedin\" class=\"heateor_sss_button_linkedin\" href=\"https:\/\/www.linkedin.com\/sharing\/share-offsite\/?url=https%3A%2F%2Fendhomelessness.org%2Fes%2Fblog%2Fcreacion-de-un-sistema-eficaz-contra-la-falta-de-vivienda-aprovechamiento-del-concurso-del-programa-coc-nofo-para-los-anos-fiscales-2024-25%2F\" title=\"Linkedin\" rel=\"nofollow noopener\" target=\"_blank\" style=\"font-size:32px!important;box-shadow:none;display:inline-block;vertical-align:middle\"><span class=\"heateor_sss_svg heateor_sss_s__default heateor_sss_s_linkedin\" style=\"background-color:#0077b5;width:35px;height:35px;border-radius:999px;display:inline-block;opacity:1;float:left;font-size:32px;box-shadow:none;display:inline-block;font-size:16px;padding:0 4px;vertical-align:middle;background-repeat:repeat;overflow:hidden;padding:0;cursor:pointer;box-sizing:content-box\"><svg style=\"display:block;border-radius:999px;\" focusable=\"false\" aria-hidden=\"true\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"100%\" height=\"100%\" viewBox=\"0 0 32 32\"><path d=\"M6.227 12.61h4.19v13.48h-4.19V12.61zm2.095-6.7a2.43 2.43 0 0 1 0 4.86c-1.344 0-2.428-1.09-2.428-2.43s1.084-2.43 2.428-2.43m4.72 6.7h4.02v1.84h.058c.56-1.058 1.927-2.176 3.965-2.176 4.238 0 5.02 2.792 5.02 6.42v7.395h-4.183v-6.56c0-1.564-.03-3.574-2.178-3.574-2.18 0-2.514 1.7-2.514 3.46v6.668h-4.187V12.61z\" fill=\"#fff\"><\/path><\/svg><\/span><\/a><a aria-label=\"X\" class=\"heateor_sss_button_x\" href=\"https:\/\/twitter.com\/intent\/tweet?text=Creaci%C3%B3n%20de%20un%20sistema%20eficaz%20contra%20la%20falta%20de%20vivienda%3A%20Aprovechamiento%20del%20concurso%20del%20programa%20CoC%20NOFO%20para%20los%20a%C3%B1os%20fiscales%202024%2F25&url=https%3A%2F%2Fendhomelessness.org%2Fes%2Fblog%2Fcreacion-de-un-sistema-eficaz-contra-la-falta-de-vivienda-aprovechamiento-del-concurso-del-programa-coc-nofo-para-los-anos-fiscales-2024-25%2F\" title=\"X\" rel=\"nofollow noopener\" target=\"_blank\" style=\"font-size:32px!important;box-shadow:none;display:inline-block;vertical-align:middle\"><span class=\"heateor_sss_svg heateor_sss_s__default heateor_sss_s_x\" style=\"background-color:#2a2a2a;width:35px;height:35px;border-radius:999px;display:inline-block;opacity:1;float:left;font-size:32px;box-shadow:none;display:inline-block;font-size:16px;padding:0 4px;vertical-align:middle;background-repeat:repeat;overflow:hidden;padding:0;cursor:pointer;box-sizing:content-box\"><svg width=\"100%\" height=\"100%\" style=\"display:block;border-radius:999px;\" focusable=\"false\" aria-hidden=\"true\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 32 32\"><path fill=\"#fff\" d=\"M21.751 7h3.067l-6.7 7.658L26 25.078h-6.172l-4.833-6.32-5.531 6.32h-3.07l7.167-8.19L6 7h6.328l4.37 5.777L21.75 7Zm-1.076 16.242h1.7L11.404 8.74H9.58l11.094 14.503Z\"><\/path><\/svg><\/span><\/a><\/div><div class=\"heateorSssClear\"><\/div><\/div>\n<\/div>\n<\/div>\n\n\n\n<div class=\"e-div e-div-1a5a32aa7dcbe57c6b9a8a8c9a37785edf82434d e-div--bi-topics\">\n<h2 class=\"wp-block-heading has-rich-black-color has-text-color has-link-color wp-elements-be6bdbd00a494032c0ae3c9d7a69a331\">Etiquetas<\/h2>\n\n\n<div class=\"e-mtf e-mtf--dlt e-mtf--taxonomy e-mtf--taxonomy-blog-tags\"><\/div><\/div>\n\n\n\n<div class=\"e-div e-div-275b8ff6f2bffd3e4cc054055156f9110887442d e-div--bi-related-post\"><style><\/style>\n<h2 class=\"wp-block-heading has-rich-black-color has-text-color has-link-color wp-elements-e435b81f6878ebba01997b7c42400d88\">Publicaciones relacionadas<\/h2>\n\n\n\n<div class=\"e-div e-div-0162dd5adc5b84600d5bea230d8c418559af071d\">\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div><\/section>\n\n<section class=\"e-stn e-stn-af33064b18769c0dcbd144d5242c41c8ff25e8a2 e-stn--related-post e-mt-60  e-mt-sm-0\"><style>@media only screen and (max-width: 9999px) {\n\t\t\t\t\t\t\t\t\t.e-stn.e-stn-af33064b18769c0dcbd144d5242c41c8ff25e8a2 { \n\t\t\t\t\t\t\t\t\t\tbackground-color: #F3F8FC; \n\t\t\t\t\t\t\t\t\t}\n\t\t\t\t\t\t\t\t}<\/style><div class=\"container\">\n<div class=\"wp-block-b3rg-row e-row row e-row--title-with-description\">\n<div class=\"wp-block-b3rg-column e-col e-col-3fd29a26ff70780ecd7ff03db8f4638045c8c9d8  col-sm-12\">\n<h2 class=\"wp-block-heading has-text-align-center\">Tambi\u00e9n le podr\u00eda interesar<\/h2>\n<\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-b3rg-row e-row row\">\n<div class=\"wp-block-b3rg-column e-col e-col-3fd29a26ff70780ecd7ff03db8f4638045c8c9d8  col-sm-12\"><div class=\"e-rlp e-rlp--dlt\" > <div class=\"e-sgp taxonomy-legisladores-y-defensores taxonomy-vivienda-asequible taxonomy-falta-de-vivienda-en-situacion-de-calle taxonomy-gobierno-estatal-y-local e-sgp--dlt  wrapper-link\" > <a class=\"b3rg-post__trigger\" href='https:\/\/endhomelessness.org\/es\/blog\/lo-que-se-necesita-para-erradicar-la-falta-de-vivienda-mas-alla-de-la-decision-de-la-corte-suprema\/' target='_self'><div class=\"e-sgp__inner\">\n<div class=\"e-div e-div-39c9483d5c365ef0cd3af0137228c52c9e3c2277 e-sgp__media\"><figure class=\"wp-block-post-featured-image\"><img decoding=\"async\" src=\"https:\/\/endhomelessness.org\/wp-content\/uploads\/2024\/10\/7432022562_8d4289be3b_o-2048x1360-2.jpg\" class=\"attachment-post-thumbnail size-post-thumbnail wp-post-image\" alt=\"Written by Marcy Thompson\" style=\"object-fit:cover;\" srcset=\"https:\/\/endhomelessness.org\/wp-content\/uploads\/2024\/10\/7432022562_8d4289be3b_o-2048x1360-2.jpg 2048w, https:\/\/endhomelessness.org\/wp-content\/uploads\/2024\/10\/7432022562_8d4289be3b_o-2048x1360-2-300x199.jpg 300w, https:\/\/endhomelessness.org\/wp-content\/uploads\/2024\/10\/7432022562_8d4289be3b_o-2048x1360-2-1024x680.jpg 1024w, https:\/\/endhomelessness.org\/wp-content\/uploads\/2024\/10\/7432022562_8d4289be3b_o-2048x1360-2-768x510.jpg 768w, https:\/\/endhomelessness.org\/wp-content\/uploads\/2024\/10\/7432022562_8d4289be3b_o-2048x1360-2-1536x1020.jpg 1536w, https:\/\/endhomelessness.org\/wp-content\/uploads\/2024\/10\/7432022562_8d4289be3b_o-2048x1360-2-575x382.jpg 575w\" sizes=\"(max-width: 2048px) 100vw, 2048px\" \/><\/figure><\/div>\n\n<div class=\"e-div e-div-9345c3010e68f662cc8801eb2da3df07e835db1c e-sgp__content\">\n<div class=\"e-div e-div-0162dd5adc5b84600d5bea230d8c418559af071d\"><div class=\"wp-block-post-date\"><time datetime=\"2024-06-21T09:00:00-04:00\">21 de junio de 2024<\/time><\/div>\n\n\n<div class=\"e-div e-div-0162dd5adc5b84600d5bea230d8c418559af071d\"><div class=\"e-mtf e-mtf--dlt  e-mtf--post-reading-time\"><div class=\"post-reading-time\"><span class=\"reading-time__time\">6<\/span> <span class=\"post-reading-time__label postfix\">min<\/span><\/div><\/div><\/div>\n<\/div>\n\n\n<div class=\"e-mtf e-mtf--dlt  e-mtf--author-details\"><div class=\"post-author\"><div class=\"post-author__avatar\"><img decoding=\"async\" src=\"https:\/\/secure.gravatar.com\/avatar\/b15d1d242f4e013b2de0f21a94a1d848dfbeadfb7dde110341ae926f9abdedad?s=96&#038;d=mm&#038;r=g\" alt=\"\"\/><\/div>                        <div class=\"post-author__content\">\n                            <p class=\"post-author__name\">Marcy Thompson<\/p>\n                        <\/div><\/div><\/div>\n\n<h2 class=\"wp-block-post-title\">Lo que se necesita para erradicar la falta de vivienda: m\u00e1s all\u00e1 de la decisi\u00f3n de la Corte Suprema<\/h2>\n\n<div class=\"wp-block-post-excerpt\"><p class=\"wp-block-post-excerpt__excerpt\">La Corte Suprema est\u00e1 a punto de emitir un fallo en el caso de la Ciudad de Grants Pass, Oreg\u00f3n contra Johnson, el primer caso importante sobre la falta de vivienda que se presenta ante la Corte Suprema desde la d\u00e9cada de 1980. El caso determinar\u00e1&#8230; <\/p><\/div>\n\n<div class=\"e-mtf e-mtf--dlt e-mtf--taxonomy e-mtf--taxonomy-blog-tags\"><\/div>\n\n<div class=\"e-mtf e-mtf--dlt  e-mtf--learn-more-label\"><span class=\"btn\"><\/span><\/div><\/div>\n<\/div><\/a><\/div><div class=\"e-sgp taxonomy-opcional taxonomy-falta-de-vivienda-en-situacion-de-calle taxonomy-continuos-de-atencion e-sgp--dlt  wrapper-link\" > <a class=\"b3rg-post__trigger\" href='https:\/\/endhomelessness.org\/es\/blog\/sesion-plenaria-de-apertura-conferencia-sobre-innovaciones-y-soluciones-para-erradicar-el-sinhogarismo-no-albergado-marzo-de-2024\/' target='_self'><div class=\"e-sgp__inner\">\n<div class=\"e-div e-div-39c9483d5c365ef0cd3af0137228c52c9e3c2277 e-sgp__media\"><figure class=\"wp-block-post-featured-image\"><img decoding=\"async\" src=\"https:\/\/endhomelessness.org\/wp-content\/uploads\/2024\/10\/support-our-work-e1611776502991-3.jpg\" class=\"attachment-post-thumbnail size-post-thumbnail wp-post-image\" alt=\"Written by Marcy Thompson\" style=\"object-fit:cover;\" srcset=\"https:\/\/endhomelessness.org\/wp-content\/uploads\/2024\/10\/support-our-work-e1611776502991-3.jpg 1200w, https:\/\/endhomelessness.org\/wp-content\/uploads\/2024\/10\/support-our-work-e1611776502991-3-300x119.jpg 300w, https:\/\/endhomelessness.org\/wp-content\/uploads\/2024\/10\/support-our-work-e1611776502991-3-1024x407.jpg 1024w, https:\/\/endhomelessness.org\/wp-content\/uploads\/2024\/10\/support-our-work-e1611776502991-3-768x305.jpg 768w, https:\/\/endhomelessness.org\/wp-content\/uploads\/2024\/10\/support-our-work-e1611776502991-3-575x229.jpg 575w\" sizes=\"(max-width: 1200px) 100vw, 1200px\" \/><\/figure><\/div>\n\n<div class=\"e-div e-div-9345c3010e68f662cc8801eb2da3df07e835db1c e-sgp__content\">\n<div class=\"e-div e-div-0162dd5adc5b84600d5bea230d8c418559af071d\"><div class=\"wp-block-post-date\"><time datetime=\"2024-03-19T08:59:00-04:00\">19 de marzo de 2024<\/time><\/div>\n\n\n<div class=\"e-div e-div-0162dd5adc5b84600d5bea230d8c418559af071d\"><div class=\"e-mtf e-mtf--dlt  e-mtf--post-reading-time\"><div class=\"post-reading-time\"><span class=\"reading-time__time\">12<\/span> <span class=\"post-reading-time__label postfix\">min<\/span><\/div><\/div><\/div>\n<\/div>\n\n\n<div class=\"e-mtf e-mtf--dlt  e-mtf--author-details\"><div class=\"post-author\"><div class=\"post-author__avatar\"><img decoding=\"async\" src=\"https:\/\/secure.gravatar.com\/avatar\/ea86b2b9f946d9233bda9c93f5134672349f8d7d350c75901efd5845c144a57d?s=96&#038;d=mm&#038;r=g\" alt=\"\"\/><\/div>                        <div class=\"post-author__content\">\n                            <p class=\"post-author__name\">Ann Oliva<\/p>\n                        <\/div><\/div><\/div>\n\n<h2 class=\"wp-block-post-title\">Sesi\u00f3n plenaria de apertura: Conferencia sobre innovaciones y soluciones para erradicar el sinhogarismo no albergado, marzo de 2024<\/h2>\n\n<div class=\"wp-block-post-excerpt\"><p class=\"wp-block-post-excerpt__excerpt\">\u00a1Buenas tardes a todos! Es sumamente gratificante verlos a todos aqu\u00ed en San Francisco para la Conferencia de la Alianza del 2024 sobre innovaciones y soluciones para erradicar el sinhogarismo no albergado&#8230;. <\/p><\/div>\n\n<div class=\"e-mtf e-mtf--dlt e-mtf--taxonomy e-mtf--taxonomy-blog-tags\"><\/div>\n\n<div class=\"e-mtf e-mtf--dlt  e-mtf--learn-more-label\"><span class=\"btn\"><\/span><\/div><\/div>\n<\/div><\/a><\/div><\/div><\/div>\n<\/div>\n<\/div><\/section>\n\n<section class=\"e-stn e-stn-158d3f83201698fefb00fac834df58bf05528a72 e-stn--subscription-form\"><div class=\"container\">\n<div class=\"wp-block-b3rg-row e-row row\">\n<div class=\"wp-block-b3rg-column e-col e-col-8afe031c32f32bbc0f030f056b33968bd5962cdb e-col--left  col-sm-12 col-lg-6\">\n<h2 class=\"wp-block-heading has-pure-white-color has-text-color has-link-color wp-elements-7991c1fe5c78877d811d75ef55460408\" id=\"h-stay-updated-solutions-stories-and-ways-to-make-an-impact\"><strong>Mant\u00e9ngase informado: Soluciones, historias y formas de generar impacto<\/strong><\/h2>\n\n\n\n<p>Reg\u00edstrese para recibir actualizaciones sobre el trabajo de la Alianza, incluyendo las \u00faltimas investigaciones, esfuerzos de promoci\u00f3n e historias reales de progreso \u2014 adem\u00e1s de formas en las que puede ayudar a impulsar un cambio duradero.<\/p>\n<\/div>\n\n\n\n<div class=\"wp-block-b3rg-column e-col e-col-6ddfe7b71def43e793d197c91d7a094da4f97b69 e-col--right e-col--email-cta-form-wrpr  col-sm-12 col-lg-6\">\n<div id=\"mc_embed_shell\">\n      <link href=\"\/\/cdn-images.mailchimp.com\/embedcode\/classic-061523.css\" rel=\"stylesheet\" type=\"text\/css\"\/>\n  <style type=\"text\/css\">\n        #mc_embed_signup{background:#fff; false;clear:left; font:14px Helvetica,Arial,sans-serif; width: 600px;}\n        \/* Add your own Mailchimp form style overrides in your site stylesheet or in this style block.\n           We recommend moving this block and the preceding CSS link to the HEAD of your HTML file. *\/\n<\/style>\n<div id=\"mc_embed_signup\">\n    <form action=\"https:\/\/endhomelessness.us9.list-manage.com\/subscribe\/post?u=466b34a51377a9504fb2ebd8f&#038;id=1cf64328bb&#038;f_id=00f7f2e0f0\" method=\"post\" id=\"mc-embedded-subscribe-form\" name=\"mc-embedded-subscribe-form\" class=\"validate\" target=\"_blank\">\n        <div id=\"mc_embed_signup_scroll\">\n            <div class=\"indicates-required\"><span class=\"asterisk\">*<\/span> indica campo obligatorio<\/div>\n            <div class=\"mc-field-group\"><label for=\"mce-EMAIL\">Direcci\u00f3n de correo electr\u00f3nico <span class=\"asterisk\">*<\/span><\/label><input type=\"email\" name=\"EMAIL\" class=\"required email\" id=\"mce-EMAIL\" required=\"\" value=\"\"\/><\/div><div class=\"mc-field-group input-group\"><strong>\u00bfC\u00f3mo deber\u00edamos comunicarnos con usted? <\/strong><ul><li><input type=\"checkbox\" name=\"group[17873][1]\" id=\"mce-group[17873]-17873-0\" value=\"\"\/><label for=\"mce-group[17873]-17873-0\">Deseo recibir semanalmente herramientas, recursos y noticias sobre la falta de vivienda<\/label><\/li><li><input type=\"checkbox\" name=\"group[17873][2]\" id=\"mce-group[17873]-17873-1\" value=\"\"\/><label for=\"mce-group[17873]-17873-1\">Deseo recibir noticias generales y actualizaciones sobre el trabajo de la Alianza<\/label><\/li><\/ul><\/div><div class=\"mc-field-group\"><label for=\"mce-FNAME\">Nombre <\/label><input type=\"text\" name=\"FNAME\" class=\" text\" id=\"mce-FNAME\" value=\"\"\/><\/div><div class=\"mc-field-group\"><label for=\"mce-LNAME\">Apellido <\/label><input type=\"text\" name=\"LNAME\" class=\" text\" id=\"mce-LNAME\" value=\"\"\/><\/div>\n<div hidden=\"\"><input type=\"hidden\" name=\"tags\" value=\"12777910\"\/><\/div>\n        <div id=\"mce-responses\" class=\"clear\">\n            <div class=\"response\" id=\"mce-error-response\" style=\"display: none;\"><\/div>\n            <div class=\"response\" id=\"mce-success-response\" style=\"display: none;\"><\/div>\n        <\/div><div aria-hidden=\"true\" style=\"position: absolute; left: -5000px;\"><input type=\"text\" name=\"b_466b34a51377a9504fb2ebd8f_1cf64328bb\" tabindex=\"-1\" value=\"\"\/><\/div><div class=\"clear\"><input type=\"submit\" name=\"subscribe\" id=\"mc-embedded-subscribe\" class=\"button\" value=\"Suscribirse\"\/><\/div>\n    <\/div>\n<\/form>\n<\/div>\n<script type=\"text\/javascript\" src=\"\/\/s3.amazonaws.com\/downloads.mailchimp.com\/js\/mc-validate.js\"><\/script><script type=\"text\/javascript\">(function($) {window.fnames = new Array(); window.ftypes = new Array();fnames[0]='EMAIL';ftypes[0]='email';fnames[1]='FNAME';ftypes[1]='text';fnames[2]='LNAME';ftypes[2]='text';fnames[12]='MMERGE12';ftypes[12]='zip';fnames[4]='MMERGE4';ftypes[4]='text';fnames[7]='CITY';ftypes[7]='text';fnames[8]='STATE';ftypes[8]='text';fnames[11]='MMERGE11';ftypes[11]='text';fnames[13]='MMERGE13';ftypes[13]='text';fnames[3]='MMERGE3';ftypes[3]='text';fnames[5]='MMERGE5';ftypes[5]='text';}(jQuery));var $mcj = jQuery.noConflict(true);<\/script><\/div>\n<\/div>\n<\/div>\n<\/div><\/section>\n","protected":false},"excerpt":{"rendered":"<p>El Departamento de Vivienda y Desarrollo Urbano de los Estados Unidos (HUD) ha puesto recientemente a disposici\u00f3n 3.524 millones de d\u00f3lares en financiaci\u00f3n a trav\u00e9s del a\u00f1o fiscal 2024&#8230;<\/p>\n","protected":false},"author":6,"featured_media":5141,"template":"","meta":{"_acf_changed":false,"show_custom_date":false,"custom_date":"","featured":false,"featured_image":0,"learn_more_label":"","image_alt_text":"","learn_more_type":"","show_popup":false,"learn_more_link_file":0,"event_date":false,"event_start_date":"","event_end_date":"","place_holder_image_url":"","post_reading_time":"4","notification_enabled":false,"notification_text":"","notification_logo":"","notification_expiration_time":0,"is_enable_transparent_header":false,"hide_from_list_view":false,"selected_taxonomy_terms":{"blog-category":[],"blog-audience":[304],"blog-best-practice":[363],"blog-key-issue":[313],"translation_priority":[64]},"selected_primary_terms":[],"learn_more_link":[],"featured_page_list":[],"notification_enabled_post_list":[],"_relevanssi_hide_post":"","_relevanssi_hide_content":"","_relevanssi_pin_for_all":"","_relevanssi_pin_keywords":"","_relevanssi_unpin_keywords":"","_relevanssi_related_keywords":"","_relevanssi_related_include_ids":"","_relevanssi_related_exclude_ids":"","_relevanssi_related_no_append":"","_relevanssi_related_not_related":"","_relevanssi_related_posts":"18859,18710,18460","_relevanssi_noindex_reason":"","inline_featured_image":false,"news_publication":"","footnotes":""},"blog-category":[],"blog-audience":[465],"blog-best-practice":[467],"blog-key-issue":[472],"class_list":["post-18614","blog","type-blog","status-publish","has-post-thumbnail","hentry","blog-audience-continuos-de-atencion","blog-best-practice-diseno-de-sistemas","blog-key-issue-financiacion-federal"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v24.7 (Yoast SEO v27.4) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Creaci\u00f3n de un sistema eficaz contra la falta de vivienda: Aprovechamiento del concurso del programa CoC NOFO para los a\u00f1os fiscales 2024\/25 - Alianza Nacional para Erradicar la Falta de Vivienda<\/title>\n<meta name=\"description\" content=\"The National Alliance to End Homelessness is a nonpartisan, nonprofit organization committed to preventing and ending homelessness in the United States.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/endhomelessness.org\/es\/blog\/creacion-de-un-sistema-eficaz-contra-la-falta-de-vivienda-aprovechamiento-del-concurso-del-programa-coc-nofo-para-los-anos-fiscales-2024-25\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Creaci\u00f3n de un sistema eficaz contra la falta de vivienda: Aprovechamiento del concurso del programa CoC NOFO para los a\u00f1os fiscales 2024\/25\" \/>\n<meta property=\"og:description\" content=\"The National Alliance to End Homelessness is a nonpartisan, nonprofit organization committed to preventing and ending homelessness in the United States.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/endhomelessness.org\/es\/blog\/creacion-de-un-sistema-eficaz-contra-la-falta-de-vivienda-aprovechamiento-del-concurso-del-programa-coc-nofo-para-los-anos-fiscales-2024-25\/\" \/>\n<meta property=\"og:site_name\" content=\"Alianza Nacional para Erradicar la Falta de Vivienda\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/naehomelessness\/\" \/>\n<meta property=\"article:modified_time\" content=\"2025-04-08T12:13:10+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/endhomelessness.org\/wp-content\/uploads\/2024\/10\/Nesbitt-Woman-typing-computer-3-1-e1531943208769.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"877\" \/>\n\t<meta property=\"og:image:height\" content=\"400\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data1\" content=\"5 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/endhomelessness.org\\\/es\\\/blog\\\/creacion-de-un-sistema-eficaz-contra-la-falta-de-vivienda-aprovechamiento-del-concurso-del-programa-coc-nofo-para-los-anos-fiscales-2024-25\\\/\",\"url\":\"https:\\\/\\\/endhomelessness.org\\\/es\\\/blog\\\/creacion-de-un-sistema-eficaz-contra-la-falta-de-vivienda-aprovechamiento-del-concurso-del-programa-coc-nofo-para-los-anos-fiscales-2024-25\\\/\",\"name\":\"Creaci\u00f3n de un sistema eficaz contra la falta de vivienda: Aprovechamiento del concurso del programa CoC NOFO para los a\u00f1os fiscales 2024\\\/25 - Alianza Nacional para Erradicar la Falta de Vivienda\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/endhomelessness.org\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/endhomelessness.org\\\/es\\\/blog\\\/creacion-de-un-sistema-eficaz-contra-la-falta-de-vivienda-aprovechamiento-del-concurso-del-programa-coc-nofo-para-los-anos-fiscales-2024-25\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/endhomelessness.org\\\/es\\\/blog\\\/creacion-de-un-sistema-eficaz-contra-la-falta-de-vivienda-aprovechamiento-del-concurso-del-programa-coc-nofo-para-los-anos-fiscales-2024-25\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/endhomelessness.org\\\/wp-content\\\/uploads\\\/2024\\\/10\\\/Nesbitt-Woman-typing-computer-3-1-e1531943208769.jpg\",\"datePublished\":\"2024-08-01T13:00:00+00:00\",\"dateModified\":\"2025-04-08T12:13:10+00:00\",\"description\":\"The National Alliance to End Homelessness is a nonpartisan, nonprofit organization committed to preventing and ending homelessness in the United States.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/endhomelessness.org\\\/es\\\/blog\\\/creacion-de-un-sistema-eficaz-contra-la-falta-de-vivienda-aprovechamiento-del-concurso-del-programa-coc-nofo-para-los-anos-fiscales-2024-25\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/endhomelessness.org\\\/es\\\/blog\\\/creacion-de-un-sistema-eficaz-contra-la-falta-de-vivienda-aprovechamiento-del-concurso-del-programa-coc-nofo-para-los-anos-fiscales-2024-25\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/endhomelessness.org\\\/es\\\/blog\\\/creacion-de-un-sistema-eficaz-contra-la-falta-de-vivienda-aprovechamiento-del-concurso-del-programa-coc-nofo-para-los-anos-fiscales-2024-25\\\/#primaryimage\",\"url\":\"https:\\\/\\\/endhomelessness.org\\\/wp-content\\\/uploads\\\/2024\\\/10\\\/Nesbitt-Woman-typing-computer-3-1-e1531943208769.jpg\",\"contentUrl\":\"https:\\\/\\\/endhomelessness.org\\\/wp-content\\\/uploads\\\/2024\\\/10\\\/Nesbitt-Woman-typing-computer-3-1-e1531943208769.jpg\",\"width\":877,\"height\":400,\"caption\":\"Nesbitt Woman typing computer\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/endhomelessness.org\\\/es\\\/blog\\\/creacion-de-un-sistema-eficaz-contra-la-falta-de-vivienda-aprovechamiento-del-concurso-del-programa-coc-nofo-para-los-anos-fiscales-2024-25\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inicio\",\"item\":\"https:\\\/\\\/endhomelessness.org\\\/es\\\/home-page-2-2-2\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Creaci\u00f3n de un sistema eficaz contra la falta de vivienda: Aprovechamiento del concurso del programa CoC NOFO para los a\u00f1os fiscales 2024\\\/25\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/endhomelessness.org\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/endhomelessness.org\\\/es\\\/\",\"name\":\"National Alliance to End Homelessness\",\"description\":\"Organizaci\u00f3n no partidista para prevenir y erradicar la falta de vivienda en EE.UU.\",\"publisher\":{\"@id\":\"https:\\\/\\\/endhomelessness.org\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/endhomelessness.org\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/endhomelessness.org\\\/es\\\/#organization\",\"name\":\"Alianza Nacional para Erradicar la Falta de Vivienda\",\"url\":\"https:\\\/\\\/endhomelessness.org\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/endhomelessness.org\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/endhomelessness.org\\\/wp-content\\\/uploads\\\/2024\\\/09\\\/logo-2.webp\",\"contentUrl\":\"https:\\\/\\\/endhomelessness.org\\\/wp-content\\\/uploads\\\/2024\\\/09\\\/logo-2.webp\",\"width\":687,\"height\":361,\"caption\":\"Alianza Nacional para Erradicar la Falta de Vivienda\"},\"image\":{\"@id\":\"https:\\\/\\\/endhomelessness.org\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/naehomelessness\\\/\",\"https:\\\/\\\/www.youtube.com\\\/@EndingHomelessness\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/national-alliance-to-end-homelessness\\\/\",\"https:\\\/\\\/instagram.com\\\/naeh_endhomelessness\"]}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Creaci\u00f3n de un sistema eficaz contra la falta de vivienda: Aprovechamiento del concurso del programa CoC NOFO para los a\u00f1os fiscales 2024\/25 - Alianza Nacional para Erradicar la Falta de Vivienda","description":"The National Alliance to End Homelessness is a nonpartisan, nonprofit organization committed to preventing and ending homelessness in the United States.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/endhomelessness.org\/es\/blog\/creacion-de-un-sistema-eficaz-contra-la-falta-de-vivienda-aprovechamiento-del-concurso-del-programa-coc-nofo-para-los-anos-fiscales-2024-25\/","og_locale":"es_ES","og_type":"article","og_title":"Creaci\u00f3n de un sistema eficaz contra la falta de vivienda: Aprovechamiento del concurso del programa CoC NOFO para los a\u00f1os fiscales 2024\/25","og_description":"The National Alliance to End Homelessness is a nonpartisan, nonprofit organization committed to preventing and ending homelessness in the United States.","og_url":"https:\/\/endhomelessness.org\/es\/blog\/creacion-de-un-sistema-eficaz-contra-la-falta-de-vivienda-aprovechamiento-del-concurso-del-programa-coc-nofo-para-los-anos-fiscales-2024-25\/","og_site_name":"Alianza Nacional para Erradicar la Falta de Vivienda","article_publisher":"https:\/\/www.facebook.com\/naehomelessness\/","article_modified_time":"2025-04-08T12:13:10+00:00","og_image":[{"width":877,"height":400,"url":"https:\/\/endhomelessness.org\/wp-content\/uploads\/2024\/10\/Nesbitt-Woman-typing-computer-3-1-e1531943208769.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Tiempo de lectura":"5 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/endhomelessness.org\/es\/blog\/creacion-de-un-sistema-eficaz-contra-la-falta-de-vivienda-aprovechamiento-del-concurso-del-programa-coc-nofo-para-los-anos-fiscales-2024-25\/","url":"https:\/\/endhomelessness.org\/es\/blog\/creacion-de-un-sistema-eficaz-contra-la-falta-de-vivienda-aprovechamiento-del-concurso-del-programa-coc-nofo-para-los-anos-fiscales-2024-25\/","name":"Creaci\u00f3n de un sistema eficaz contra la falta de vivienda: Aprovechamiento del concurso del programa CoC NOFO para los a\u00f1os fiscales 2024\/25 - Alianza Nacional para Erradicar la Falta de Vivienda","isPartOf":{"@id":"https:\/\/endhomelessness.org\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/endhomelessness.org\/es\/blog\/creacion-de-un-sistema-eficaz-contra-la-falta-de-vivienda-aprovechamiento-del-concurso-del-programa-coc-nofo-para-los-anos-fiscales-2024-25\/#primaryimage"},"image":{"@id":"https:\/\/endhomelessness.org\/es\/blog\/creacion-de-un-sistema-eficaz-contra-la-falta-de-vivienda-aprovechamiento-del-concurso-del-programa-coc-nofo-para-los-anos-fiscales-2024-25\/#primaryimage"},"thumbnailUrl":"https:\/\/endhomelessness.org\/wp-content\/uploads\/2024\/10\/Nesbitt-Woman-typing-computer-3-1-e1531943208769.jpg","datePublished":"2024-08-01T13:00:00+00:00","dateModified":"2025-04-08T12:13:10+00:00","description":"The National Alliance to End Homelessness is a nonpartisan, nonprofit organization committed to preventing and ending homelessness in the United States.","breadcrumb":{"@id":"https:\/\/endhomelessness.org\/es\/blog\/creacion-de-un-sistema-eficaz-contra-la-falta-de-vivienda-aprovechamiento-del-concurso-del-programa-coc-nofo-para-los-anos-fiscales-2024-25\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/endhomelessness.org\/es\/blog\/creacion-de-un-sistema-eficaz-contra-la-falta-de-vivienda-aprovechamiento-del-concurso-del-programa-coc-nofo-para-los-anos-fiscales-2024-25\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/endhomelessness.org\/es\/blog\/creacion-de-un-sistema-eficaz-contra-la-falta-de-vivienda-aprovechamiento-del-concurso-del-programa-coc-nofo-para-los-anos-fiscales-2024-25\/#primaryimage","url":"https:\/\/endhomelessness.org\/wp-content\/uploads\/2024\/10\/Nesbitt-Woman-typing-computer-3-1-e1531943208769.jpg","contentUrl":"https:\/\/endhomelessness.org\/wp-content\/uploads\/2024\/10\/Nesbitt-Woman-typing-computer-3-1-e1531943208769.jpg","width":877,"height":400,"caption":"Nesbitt Woman typing computer"},{"@type":"BreadcrumbList","@id":"https:\/\/endhomelessness.org\/es\/blog\/creacion-de-un-sistema-eficaz-contra-la-falta-de-vivienda-aprovechamiento-del-concurso-del-programa-coc-nofo-para-los-anos-fiscales-2024-25\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inicio","item":"https:\/\/endhomelessness.org\/es\/home-page-2-2-2\/"},{"@type":"ListItem","position":2,"name":"Creaci\u00f3n de un sistema eficaz contra la falta de vivienda: Aprovechamiento del concurso del programa CoC NOFO para los a\u00f1os fiscales 2024\/25"}]},{"@type":"WebSite","@id":"https:\/\/endhomelessness.org\/es\/#website","url":"https:\/\/endhomelessness.org\/es\/","name":"National Alliance to End Homelessness","description":"Organizaci\u00f3n no partidista para prevenir y erradicar la falta de vivienda en EE.UU.","publisher":{"@id":"https:\/\/endhomelessness.org\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/endhomelessness.org\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/endhomelessness.org\/es\/#organization","name":"Alianza Nacional para Erradicar la Falta de Vivienda","url":"https:\/\/endhomelessness.org\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/endhomelessness.org\/es\/#\/schema\/logo\/image\/","url":"https:\/\/endhomelessness.org\/wp-content\/uploads\/2024\/09\/logo-2.webp","contentUrl":"https:\/\/endhomelessness.org\/wp-content\/uploads\/2024\/09\/logo-2.webp","width":687,"height":361,"caption":"Alianza Nacional para Erradicar la Falta de Vivienda"},"image":{"@id":"https:\/\/endhomelessness.org\/es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/naehomelessness\/","https:\/\/www.youtube.com\/@EndingHomelessness","https:\/\/www.linkedin.com\/company\/national-alliance-to-end-homelessness\/","https:\/\/instagram.com\/naeh_endhomelessness"]}]}},"_links":{"self":[{"href":"https:\/\/endhomelessness.org\/es\/wp-json\/wp\/v2\/blog\/18614","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/endhomelessness.org\/es\/wp-json\/wp\/v2\/blog"}],"about":[{"href":"https:\/\/endhomelessness.org\/es\/wp-json\/wp\/v2\/types\/blog"}],"author":[{"embeddable":true,"href":"https:\/\/endhomelessness.org\/es\/wp-json\/wp\/v2\/users\/6"}],"version-history":[{"count":0,"href":"https:\/\/endhomelessness.org\/es\/wp-json\/wp\/v2\/blog\/18614\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/endhomelessness.org\/es\/wp-json\/wp\/v2\/media\/5141"}],"wp:attachment":[{"href":"https:\/\/endhomelessness.org\/es\/wp-json\/wp\/v2\/media?parent=18614"}],"wp:term":[{"taxonomy":"blog-category","embeddable":true,"href":"https:\/\/endhomelessness.org\/es\/wp-json\/wp\/v2\/blog-category?post=18614"},{"taxonomy":"blog-audience","embeddable":true,"href":"https:\/\/endhomelessness.org\/es\/wp-json\/wp\/v2\/blog-audience?post=18614"},{"taxonomy":"blog-best-practice","embeddable":true,"href":"https:\/\/endhomelessness.org\/es\/wp-json\/wp\/v2\/blog-best-practice?post=18614"},{"taxonomy":"blog-key-issue","embeddable":true,"href":"https:\/\/endhomelessness.org\/es\/wp-json\/wp\/v2\/blog-key-issue?post=18614"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}